{"id":2377,"date":"2018-09-26T14:00:53","date_gmt":"2018-09-26T12:00:53","guid":{"rendered":"https:\/\/timintralog.com\/?p=2377"},"modified":"2020-12-15T20:58:12","modified_gmt":"2020-12-15T19:58:12","slug":"gemeinsam-fuer-ihren-erfolg","status":"publish","type":"post","link":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/","title":{"rendered":"Gemeinsam f\u00fcr Ihren Erfolg!"},"content":{"rendered":"<p><strong>TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018<\/strong><\/p>\n<p>Unter dem Motto \u201eDigitales trifft Reales\u201c versammelt sich die Logistikbranche vom 17. bis 19. Oktober 2018 auf dem Deutschen Logistik-Kongress in Berlin. Der Veranstalter verspricht den gr\u00f6\u00dften branchen\u00fcbergreifenden Dialog zu Logistik und Supply Chain Management.<\/p>\n<p>Wir bringen dieses Jahr sehr gute Neuigkeiten mit nach Berlin!<\/p>\n<p>Seit August sind wir Teil der Transporeon Group und erweitern damit unser Angebot an innovativen Big-Data-Anwendungen, cloudbasierten Transportlogistik-L\u00f6sungen und datengetriebenen Gesch\u00e4ftsmodellen. In jeder Hinsicht also eine Win-Win-Situation, die uns in der Unterst\u00fctzung Ihrer digitalen Anforderungen einen enormen Schritt weiterbringt.<\/p>\n<p>Unser Gesch\u00e4ftsbereich \u201eLager-&amp; Intralogistik\u201c wird zu \u201eTIM INTRALOG\u201c und damit zu einer eigenst\u00e4ndigen Einheit am Markt. Damit st\u00e4rken wir das F\u00fchrungsteam mit seiner kompetenten und hochspezialisierten Mannschaft auf dem bereits eingeschlage\u00adnen Wachstumskurs. Das Angebot bleibt gleich: ma\u00dfgeschneiderte L\u00f6sungen rund um die Planung, Optimierung und Realisierung von Lagern und Distributionszentren.<\/p>\n<p>Bei allem Neuen, halten wir an Altbew\u00e4hrtem fest! Der Standort bleibt Mannheim. Die Ihnen vertrauten Teammitglieder sind unver\u00e4ndert f\u00fcr Sie da. Umfassende End-to-End-L\u00f6sungen erarbeiten wir auch weiterhin in enger Zusam\u00admenarbeit.<\/p>\n<p>Sind Sie vom 17. bis 19. Oktober 2018 in Berlin dabei? Dann diskutieren wir gerne mit Ihnen, welche Vorteile Sie von unserer neuen Unternehmensstruktur erwarten k\u00f6nnen.<\/p>\n<p>Sie finden uns am Stand P\/08 in Raum Potsdam II.<\/p>\n<p>Wir freuen uns auf Sie!<\/p>\n<p><strong>Ihre Ansprechpartnerin:<\/strong><br \/>\nElke Gapp<br \/>\n<a href=\"tel:+4962115044852\">+49 (0)621 150 448 52<\/a><br \/>\n<a href=\"mailto:event@timintralog.de\">event@timintralog.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018 Unter dem Motto \u201eDigitales trifft Reales\u201c versammelt sich die Logistikbranche vom 17. bis 19. Oktober 2018 auf dem Deutschen Logistik-Kongress in Berlin. Der Veranstalter verspricht den gr\u00f6\u00dften branchen\u00fcbergreifenden Dialog zu Logistik und Supply Chain Management. Wir bringen dieses Jahr sehr gute Neuigkeiten mit nach Berlin! [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blog - Gemeinsam f\u00fcr Ihren Erfolg!<\/title>\n<meta name=\"description\" content=\"TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blog - Gemeinsam f\u00fcr Ihren Erfolg!\" \/>\n<meta property=\"og:description\" content=\"TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/\" \/>\n<meta property=\"og:site_name\" content=\"TIM INTRALOG.\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-26T12:00:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-15T19:58:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/07\/news-bvl-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1892\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alexander Emmerich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alexander Emmerich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/\"},\"author\":{\"name\":\"Alexander Emmerich\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#\\\/schema\\\/person\\\/76b6ebcb53d413efdd1da6224c832112\"},\"headline\":\"Gemeinsam f\u00fcr Ihren Erfolg!\",\"datePublished\":\"2018-09-26T12:00:53+00:00\",\"dateModified\":\"2020-12-15T19:58:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/\"},\"wordCount\":239,\"publisher\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timintralog.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/news-bvl-2018.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/\",\"url\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/\",\"name\":\"Blog - Gemeinsam f\u00fcr Ihren Erfolg!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timintralog.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/news-bvl-2018.jpg\",\"datePublished\":\"2018-09-26T12:00:53+00:00\",\"dateModified\":\"2020-12-15T19:58:12+00:00\",\"description\":\"TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/timintralog.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/news-bvl-2018.jpg\",\"contentUrl\":\"https:\\\/\\\/timintralog.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/news-bvl-2018.jpg\",\"width\":2500,\"height\":1892,\"caption\":\"Beitragsbild BVL 2018\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/gemeinsam-fuer-ihren-erfolg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/timintralog.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemeinsam f\u00fcr Ihren Erfolg!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/timintralog.com\\\/de\\\/\",\"name\":\"TIM INTRALOG.\",\"description\":\"Lager- und Intralogistik Beratung\",\"publisher\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/timintralog.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#organization\",\"name\":\"TIM INTRALOG.\",\"url\":\"https:\\\/\\\/timintralog.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/timintralog.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/timintralog.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/logo.svg\",\"width\":552,\"height\":81,\"caption\":\"TIM INTRALOG.\"},\"image\":{\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/timintralog.com\\\/de\\\/#\\\/schema\\\/person\\\/76b6ebcb53d413efdd1da6224c832112\",\"name\":\"Alexander Emmerich\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d07d502ae1bfee7c4648a8238c688fdff35b837e3f2a2076f2974c7fb487c89?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d07d502ae1bfee7c4648a8238c688fdff35b837e3f2a2076f2974c7fb487c89?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d07d502ae1bfee7c4648a8238c688fdff35b837e3f2a2076f2974c7fb487c89?s=96&d=mm&r=g\",\"caption\":\"Alexander Emmerich\"},\"url\":\"https:\\\/\\\/timintralog.com\\\/de\\\/blog\\\/author\\\/a-emmerich\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blog - Gemeinsam f\u00fcr Ihren Erfolg!","description":"TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/","og_locale":"de_DE","og_type":"article","og_title":"Blog - Gemeinsam f\u00fcr Ihren Erfolg!","og_description":"TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018.","og_url":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/","og_site_name":"TIM INTRALOG.","article_published_time":"2018-09-26T12:00:53+00:00","article_modified_time":"2020-12-15T19:58:12+00:00","og_image":[{"width":2500,"height":1892,"url":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/07\/news-bvl-2018.jpg","type":"image\/jpeg"}],"author":"Alexander Emmerich","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Alexander Emmerich","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#article","isPartOf":{"@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/"},"author":{"name":"Alexander Emmerich","@id":"https:\/\/timintralog.com\/de\/#\/schema\/person\/76b6ebcb53d413efdd1da6224c832112"},"headline":"Gemeinsam f\u00fcr Ihren Erfolg!","datePublished":"2018-09-26T12:00:53+00:00","dateModified":"2020-12-15T19:58:12+00:00","mainEntityOfPage":{"@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/"},"wordCount":239,"publisher":{"@id":"https:\/\/timintralog.com\/de\/#organization"},"image":{"@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#primaryimage"},"thumbnailUrl":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/07\/news-bvl-2018.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/","url":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/","name":"Blog - Gemeinsam f\u00fcr Ihren Erfolg!","isPartOf":{"@id":"https:\/\/timintralog.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#primaryimage"},"image":{"@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#primaryimage"},"thumbnailUrl":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/07\/news-bvl-2018.jpg","datePublished":"2018-09-26T12:00:53+00:00","dateModified":"2020-12-15T19:58:12+00:00","description":"TIM CONSULT pr\u00e4sentiert neue Unternehmensstruktur auf dem Deutschen Logistik-Kongress 2018.","breadcrumb":{"@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#primaryimage","url":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/07\/news-bvl-2018.jpg","contentUrl":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/07\/news-bvl-2018.jpg","width":2500,"height":1892,"caption":"Beitragsbild BVL 2018"},{"@type":"BreadcrumbList","@id":"https:\/\/timintralog.com\/de\/blog\/gemeinsam-fuer-ihren-erfolg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/timintralog.com\/de\/"},{"@type":"ListItem","position":2,"name":"Gemeinsam f\u00fcr Ihren Erfolg!"}]},{"@type":"WebSite","@id":"https:\/\/timintralog.com\/de\/#website","url":"https:\/\/timintralog.com\/de\/","name":"TIM INTRALOG.","description":"Lager- und Intralogistik Beratung","publisher":{"@id":"https:\/\/timintralog.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/timintralog.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/timintralog.com\/de\/#organization","name":"TIM INTRALOG.","url":"https:\/\/timintralog.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/timintralog.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/02\/logo.svg","contentUrl":"https:\/\/timintralog.com\/wp-content\/uploads\/2020\/02\/logo.svg","width":552,"height":81,"caption":"TIM INTRALOG."},"image":{"@id":"https:\/\/timintralog.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/timintralog.com\/de\/#\/schema\/person\/76b6ebcb53d413efdd1da6224c832112","name":"Alexander Emmerich","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7d07d502ae1bfee7c4648a8238c688fdff35b837e3f2a2076f2974c7fb487c89?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d07d502ae1bfee7c4648a8238c688fdff35b837e3f2a2076f2974c7fb487c89?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d07d502ae1bfee7c4648a8238c688fdff35b837e3f2a2076f2974c7fb487c89?s=96&d=mm&r=g","caption":"Alexander Emmerich"},"url":"https:\/\/timintralog.com\/de\/blog\/author\/a-emmerich\/"}]}},"_links":{"self":[{"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/posts\/2377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/comments?post=2377"}],"version-history":[{"count":0,"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/posts\/2377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/media\/2379"}],"wp:attachment":[{"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/media?parent=2377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/categories?post=2377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timintralog.com\/de\/wp-json\/wp\/v2\/tags?post=2377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}